{"id":127,"date":"2017-11-30T18:12:29","date_gmt":"2017-11-30T18:12:29","guid":{"rendered":"http:\/\/c-w-stolte.de\/?page_id=127"},"modified":"2023-01-18T12:23:56","modified_gmt":"2023-01-18T11:23:56","slug":"datenschutz","status":"publish","type":"page","link":"https:\/\/c-w-stolte.de\/en\/datenschutz","title":{"rendered":"Datenschutz"},"content":{"rendered":"<h2><span style=\"font-family: arial, helvetica, sans-serif; font-size: 24pt;\"><span style=\"color: #ff8e38;\">Datenschutzerkl\u00e4rung<\/span><\/span><\/h2>\n<p>Die nachfol<span style=\"color: #333333;\">gende Datenschutzerkl\u00e4rung gilt f\u00fcr die Nutz<\/span>ung der Webseite <a href=\"https:\/\/c-w-stolte.de\/en\/\">www.c-w-stolte.de<\/a> (nachfolgend \u201eWebsite\u201c).<\/p>\n<p>Wir messen dem Datenschutz gro\u00dfe Bedeutung bei. Die Erhebung und Verarbeitung Ihrer personenbezogenen Daten geschieht unter Beachtung der geltenden datenschutzrechtlichen Vorschriften, insbesondere der EU-Datenschutzgrundverordnung (DSGVO). Wir erheben und verarbeiten Ihre personenbezogenen Daten, um Ihnen das oben genannten Portal anbieten zu k\u00f6nnen. Diese Erkl\u00e4rung beschreibt, wie und zu welchem Zweck Ihre Daten erfasst und genutzt werden und welche Wahlm\u00f6glichkeiten Sie im Zusammenhang mit pers\u00f6nlichen Daten haben.<\/p>\n<p>Durch Ihre Verwendung dieser Website stimmen Sie der Erfassung, Nutzung und \u00dcbertragung Ihrer Daten gem\u00e4\u00df dieser Datenschutzerkl\u00e4rung zu.<\/p>\n<h2><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt; color: #ff6600;\"><strong>Verantwortliche Stelle <\/strong><\/span><\/h2>\n<p>Verantwortliche Stelle f\u00fcr die Erhebung, Verarbeitung und Nutzung Ihrer personenbezogenen Daten im Sinne der DSGVO ist<\/p>\n<p><span style=\"color: #ff6600;\">C.W. Stolte GmbH &amp; Co. K.G<\/span>.<\/p>\n<p>Koenigstrasse 156 B<\/p>\n<p>D- 42853 Remscheid<\/p>\n<p>Telefon: (0 21 91) 29 20 39<\/p>\n<p>E-Mail: <a href=\"mailto:info@c-w-stolte.de\">info@c-w-stolte.de<\/a><\/p>\n<p>Sofern Sie der Erhebung, Verarbeitung oder Nutzung Ihrer Daten durch uns nach Ma\u00dfgabe dieser Datenschutzbestimmungen insgesamt oder f\u00fcr einzelne Ma\u00dfnahmen widersprechen wollen, k\u00f6nnen Sie Ihren Widerspruch an oben genannte verantwortliche Stelle richten.<\/p>\n<p>Sie k\u00f6nnen diese Datenschutzerkl\u00e4rung jederzeit speichern und ausdrucken.<\/p>\n<p><span style=\"color: #ff6600; font-family: arial, helvetica, sans-serif; font-size: 14pt;\"><strong>Allgemeine Nutzung der Webseite<\/strong><\/span><\/p>\n<p><span style=\"color: #ff6600; font-family: arial, helvetica, sans-serif; font-size: 14pt;\"><strong>Zugriffsdaten <\/strong><\/span><\/p>\n<p>Wir sammeln Informationen \u00fcber Sie, wenn Sie diese Webseite nutzen. Wir erfassen automatisch Informationen \u00fcber Ihr Nutzungsverhalten und Ihre Interaktion mit uns und registrieren Daten zu Ihrem Computer oder Mobilger\u00e4t. Wir erheben, speichern und nutzen Daten \u00fcber jeden Zugriff auf unser Onlineangebot (sogenannte Serverlogfiles). Zu den Zugriffsdaten geh\u00f6ren Name und URL der abgerufenen Datei, Datum und Uhrzeit des Abrufs, \u00fcbertragene Datenmenge, Meldung \u00fcber erfolgreichen Abruf (HTTP response code), Browsertyp und Browserversion, Betriebssystem, Referrer URL (d.h. die zuvor besuchte Seite), IP-Adresse und der anfragende Provider. Wir nutzen diese Protokolldaten ohne Zuordnung zu Ihrer Person oder sonstiger Profilerstellung f\u00fcr statistische Auswertungen zum Zweck des Betriebs, der Sicherheit und der Optimierung unseres Onlineangebotes, aber auch zur anonymen Erfassung der Anzahl der Besucher auf unserer Webseite (traffic) sowie zu Umfang und zur Art der Nutzung unserer Webseite und Dienste, ebenso zu Abrechnungszwecken, um die Anzahl der von Kooperationspartnern erhaltenen Clicks zu messen. Aufgrund dieser Informationen k\u00f6nnen wir personalisierte und standortbezogene Inhalte zur Verf\u00fcgung stellen und den Datenverkehr analysieren, Fehler suchen und beheben und unsere Dienste verbessern. Wir behalten uns vor, die Protokolldaten nachtr\u00e4glich zu \u00fcberpr\u00fcfen, wenn aufgrund konkreter Anhaltspunkte der berechtigte Verdacht einer rechtswidrigen Nutzung besteht. IP-Adressen speichern wir f\u00fcr einen begrenzten Zeitraum in den Logfiles, wenn dies f\u00fcr Sicherheitszwecke erforderlich oder f\u00fcr die Leistungserbringung oder die Abrechnung einer Leistung n\u00f6tig ist, z. B. wenn Sie eines unserer Angebote nutzen. Nach Abbruch des Vorgangs der Bestellung oder nach Zahlungseingang l\u00f6schen wir die IP-Adresse, wenn diese f\u00fcr Sicherheitszwecke nicht mehr erforderlich sind. IP-Adressen speichern wir auch dann, wenn wir den konkreten Verdacht einer Straftat im Zusammenhang mit der Nutzung unserer Website haben. Au\u00dferdem speichern wir als Teil Ihres Accounts das Datum Ihres letzten Besuchs (z.B. bei Registrierung, Login, Klicken von Links etc.).<\/p>\n<p><span style=\"color: #ff6600; font-family: arial, helvetica, sans-serif; font-size: 14pt;\"><strong>Datenerhebung und -verwendung zur Vertragsabwicklung und bei Er\u00f6ffnung eines Kundenkontos<\/strong><\/span><\/p>\n<p>\u200b<\/p>\n<p>Wir erheben personenbezogene Daten, wenn Sie uns diese im Rahmen Ihrer Bestellung, bei einer Kontaktaufnahme mit uns (z.B. per Kontaktformular oder E-Mail) oder bei Er\u00f6ffnung eines Kundenkontos freiwillig mitteilen. Welche Daten erhoben werden, ist aus den jeweiligen Eingabeformularen ersichtlich. Wir verwenden die von ihnen mitgeteilten Daten zur Vertragsabwicklung und Bearbeitung Ihrer Anfragen. Nach vollst\u00e4ndiger Abwicklung des Vertrages oder L\u00f6schung Ihres Kundenkontos werden Ihre Daten f\u00fcr die weitere Verwendung gesperrt und nach Ablauf der steuer- und handelsrechtlichen Aufbewahrungsfristen gel\u00f6scht, sofern Sie nicht ausdr\u00fccklich in eine weitere Nutzung Ihrer Daten eingewilligt haben oder wir uns eine dar\u00fcberhinausgehende Datenverwendung vorbehalten, die gesetzlich erlaubt ist und \u00fcber die wir Sie nachstehend informieren. Die L\u00f6schung Ihres Kundenkontos ist jederzeit m\u00f6glich und kann entweder durch eine Nachricht an die unten beschriebene Kontaktm\u00f6glichkeit oder \u00fcber eine daf\u00fcr vorgesehene Funktion im Kundenkonto erfolgen.<\/p>\n<p>\u200b<\/p>\n<p><span style=\"font-size: 14pt; font-family: arial, helvetica, sans-serif; color: #ff6600;\"><strong>Datenweitergabe zur Vertragserf\u00fcllung<\/strong><\/span><\/p>\n<p>\u200b<\/p>\n<p>Zur Vertragserf\u00fcllung geben wir Ihre Daten an das mit der Lieferung beauftragte Versandunternehmen weiter, soweit dies zur Lieferung bestellter Waren erforderlich ist. Je nachdem, welchen Zahlungsdienstleister Sie im Bestellprozess ausw\u00e4hlen, geben wir zur Abwicklung von Zahlungen die hierf\u00fcr erhobenen Zahlungsdaten an das mit der Zahlung beauftragte Kreditinstitut und ggf. von uns beauftragte Zahlungsdienstleister weiter bzw. an den ausgew\u00e4hlten Zahlungsdienst. Zum Teil erheben die ausgew\u00e4hlten Zahlungsdienstleister diese Daten auch selbst, soweit Sie dort ein Konto anlegen. In diesem Fall m\u00fcssen Sie sich im Bestellprozess mit Ihren Zugangsdaten bei dem Zahlungsdienstleister anmelden. Es gilt insoweit die Datenschutzerkl\u00e4rung des jeweiligen Zahlungsdienstleisters.<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt; color: #ff6600;\"><strong>Verwendung von Cookies<\/strong><\/span><\/p>\n<p>Um den Besuch unserer Website attraktiv zu gestalten und die Nutzung bestimmter Funktionen zu erm\u00f6glichen, verwenden wir auf verschiedenen Seiten sogenannte Cookies. Hierbei handelt es sich um kleine Textdateien, die auf Ihrem Endger\u00e4t gespeichert werden. Einige der von uns verwendeten Cookies werden nach Ende der Browser-Sitzung, also nach Schlie\u00dfen Ihres Browsers, wieder gel\u00f6scht (sog. Sitzungs-Cookies). Andere Cookies verbleiben auf Ihrem Endger\u00e4t und erm\u00f6glichen uns, Ihren Browser beim n\u00e4chsten Besuch wiederzuerkennen (persistente Cookies). Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das Setzen von Cookies informiert werden und einzeln \u00fcber deren Annahme entscheiden oder die Annahme von Cookies f\u00fcr bestimmte F\u00e4lle oder generell ausschlie\u00dfen. Bei der Nichtannahme von Cookies kann die Funktionalit\u00e4t unserer Website eingeschr\u00e4nkt sein.<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt; color: #ff6600;\"><strong>\u00a0Google Analytics<\/strong><\/span><\/p>\n<p>Wir benutzen Google Analytics, einen Webanalysedienst der Google Inc. (\u201eGoogle\u201c). Google Analytics verwendet sog. \u201eCookies\u201c, Textdateien, die auf Ihrem Computer gespeichert werden und die eine Analyse der Benutzung der Website durch Sie erm\u00f6glichen. Die durch den Cookie erzeugten Informationen \u00fcber Benutzung dieser Website durch die Seitenbesucher werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert.<\/p>\n<p>Im Falle der Aktivierung der IP-Anonymisierung auf dieser Webseite, wird Ihre IP-Adresse von Google jedoch innerhalb von Mitgliedstaaten der Europ\u00e4ischen Union oder in anderen Vertragsstaaten des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum zuvor gek\u00fcrzt. Nur in Ausnahmef\u00e4llen wird die volle IP-Adresse an einen Server von Google in den USA \u00fcbertragen und dort gek\u00fcrzt. Die IP-Anonymisierung ist auf dieser Website aktiv. In unserem Auftrag wird Google diese Informationen benutzen, um die Nutzung der Website durch Sie auszuwerten, um Reports \u00fcber die Websiteaktivit\u00e4ten zusammenzustellen und um weitere mit der Websitenutzung und der Internetnutzung verbundene Dienstleistungen uns gegen\u00fcber zu erbringen.<\/p>\n<p>Die im Rahmen von Google Analytics von Ihrem Browser \u00fcbermittelte IP-Adresse wird nicht mit anderen Daten von Google zusammengef\u00fchrt. Sie k\u00f6nnen die Speicherung der Cookies durch eine entsprechende Einstellung Ihrer Browser-Software verhindern; wir weisen Sie jedoch darauf hin, dass Sie in diesem Fall gegebenenfalls nicht s\u00e4mtliche Funktionen dieser Website vollumf\u00e4nglich werden nutzen k\u00f6nnen.<\/p>\n<p>Sie k\u00f6nnen dar\u00fcber hinaus die Erfassung der durch das Cookie erzeugten und auf ihre Nutzung der Website bezogenen Daten (inkl. Ihrer IP-Adresse) an Google sowie die Verarbeitung dieser Daten durch Google verhindern, indem Sie das unter dem folgenden Link verf\u00fcgbare Browser-Plugin herunterladen und installieren: <a href=\"http:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\">http:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a>.<\/p>\n<p>Alternativ zum Browser-Plugin oder innerhalb von Browsern auf mobilen Ger\u00e4ten k\u00f6nnen Sie auf den folgenden Link klicken, um ein Opt-Out-Cookie zu setzen, der die Erfassung durch Google Analytics innerhalb dieser Website zuk\u00fcnftig verhindert dieses Opt-Out-Cookie funktioniert nur in diesem Browser und nur f\u00fcr diese Domain. L\u00f6schen Sie die Cookies in Ihrem Browser, m\u00fcssen Sie diesen Link erneut klicken.<\/p>\n<h3><span style=\"font-family: arial, helvetica, sans-serif; color: #ff6600;\">Verwendung von Google Maps<\/span><\/h3>\n<p>Diese Website benutzt Google Maps zur Darstellung eines Lageplanes. Google Maps wird von Google Inc., 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA betrieben. Durch die Nutzung dieser Website erkl\u00e4ren Sie sich mit der Erfassung, Bearbeitung sowie der Nutzung der automatisch erhobenen sowie der von Ihnen eingegeben Daten durch Google, einer seiner Vertreter, oder Drittanbieter einverstanden.<\/p>\n<p>Die Nutzungsbedingungen f\u00fcr Google Maps finden Sie unter\u00a0: <a href=\"https:\/\/www.google.com\/intl\/de_de\/help\/terms_maps.html\">https:\/\/www.google.com\/intl\/de_de\/help\/terms_maps.html<\/a><\/p>\n<p>Ausf\u00fchrliche Details finden Sie im Datenschutz-Center von google.de:\u00a0<a href=\"https:\/\/policies.google.com\/privacy?hl=de&amp;gl=de\">https:\/\/policies.google.com\/privacy?hl=de&amp;gl=de<\/a><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt; color: #ff6600;\"><strong>Rechtsgrundlagen und Speicherdauer <\/strong><\/span><\/p>\n<p>Rechtsgrundlage der Datenverarbeitung nach den vorstehenden Ziffern ist Art 6 Abs. 1 Buchstabe f) DSGVO. Unsere Interessen an der Datenverarbeitung sind insbesondere die Sicherstellung des Betriebs und der Sicherheit der Webseite, die Untersuchung der Art und Weise der Nutzung der Webseite durch Besucher, und die Vereinfachung der Nutzung der Webseite.<\/p>\n<p>Sofern nicht spezifisch angegeben speichern wir personenbezogene Daten nur so lange, wie dies zur Erf\u00fcllung der verfolgten Zwecke notwendig ist.<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt; color: #ff6600;\"><strong>Ihre Rechte als von der Datenverarbeitung Betroffener <\/strong><\/span><\/p>\n<p>Nach den anwendbaren Gesetzen haben Sie verschiedene Rechte bez\u00fcglich ihrer personenbezogenen Daten. M\u00f6chten Sie diese Rechte geltend machen, so richten Sie Ihre Anfrage bitte per E-Mail oder per Post unter eindeutiger Identifizierung Ihrer Person an die in Ziffer 1 genannte Adresse. Nachfolgend finden Sie eine \u00dcbersicht \u00fcber Ihre Rechte.<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif; color: #ff6600; font-size: 14pt;\"><strong>Recht auf Best\u00e4tigung und Auskunft <\/strong><\/span><\/p>\n<p>Sie haben jederzeit das Recht, von uns eine Best\u00e4tigung dar\u00fcber zu erhalten, ob Sie betreffende personenbezogene Daten verarbeitet werden. Ist dies der Fall, so haben Sie das Recht, von uns eine unentgeltliche Auskunft \u00fcber die zu Ihnen gespeicherten personenbezogenen Daten nebst einer Kopie dieser Daten zu erlangen. Des Weiteren besteht ein Recht auf folgende Informationen:<\/p>\n<ol>\n<li>die Verarbeitungszwecke;<\/li>\n<li>die Kategorien personenbezogener Daten, die verarbeitet werden;<\/li>\n<li>die Empf\u00e4nger oder Kategorien von Empf\u00e4ngern, gegen\u00fcber denen die personenbezogenen Daten offengelegt worden sind oder noch offengelegt werden, insbesondere bei Empf\u00e4ngern in Drittl\u00e4ndern oder bei internationalen Organisationen;<\/li>\n<li>falls m\u00f6glich die geplante Dauer, f\u00fcr die die personenbezogenen Daten gespeichert werden, oder, falls dies nicht m\u00f6glich ist, die Kriterien f\u00fcr die Festlegung dieser Dauer;<\/li>\n<li>das Bestehen eines Rechts auf Berichtigung oder L\u00f6schung der Sie betreffenden personenbezogenen Daten oder auf Einschr\u00e4nkung der Verarbeitung durch den Verantwortlichen oder eines Widerspruchsrechts gegen diese Verarbeitung;<\/li>\n<li>das Bestehen eines Beschwerderechts bei einer Aufsichtsbeh\u00f6rde;<\/li>\n<li>wenn die personenbezogenen Daten nicht bei Ihnen erhoben werden, alle verf\u00fcgbaren Informationen \u00fcber die Herkunft der Daten;<\/li>\n<li>das Bestehen einer automatisierten Entscheidungsfindung einschlie\u00dflich Profiling gem\u00e4\u00df Artikel 22 Abs\u00e4tze 1 und 4 DSGVO und \u2013 zumindest in diesen F\u00e4llen \u2013 aussagekr\u00e4ftige Informationen \u00fcber die involvierte Logik sowie die Tragweite und die angestrebten Auswirkungen einer derartigen Verarbeitung f\u00fcr Sie.<\/li>\n<\/ol>\n<p>Werden personenbezogene Daten an ein Drittland oder an eine internationale Organisation \u00fcbermittelt, so haben Sie das Recht, \u00fcber die geeigneten Garantien gem\u00e4\u00df Artikel 46 DSGVO im Zusammenhang mit der \u00dcbermittlung unterrichtet zu werden.<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt; color: #ff6600;\"><strong>Recht auf Berichtigung <\/strong><\/span><\/p>\n<p>Sie haben das Recht, von uns unverz\u00fcglich die Berichtigung Sie betreffender unrichtiger personenbezogener Daten zu verlangen. Unter Ber\u00fccksichtigung der Zwecke der haben Sie das Recht, die Vervollst\u00e4ndigung unvollst\u00e4ndiger personenbezogener Daten \u2013 auch mittels einer erg\u00e4nzenden Erkl\u00e4rung \u2013 zu verlangen.<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt; color: #ff6600;\"><strong>Recht auf L\u00f6schung (\u201eRecht auf Vergessenwerden\u201c) <\/strong><\/span><\/p>\n<p>Sie haben das Recht, von uns zu verlangen, dass Sie betreffende personenbezogene Daten unverz\u00fcglich gel\u00f6scht werden, und wir sind verpflichtet, personenbezogene Daten unverz\u00fcglich zu l\u00f6schen, sofern einer der folgenden Gr\u00fcnde zutrifft:<\/p>\n<ol>\n<li>Die personenbezogenen Daten sind f\u00fcr die Zwecke, f\u00fcr die sie erhoben oder auf sonstige Weise verarbeitet wurden, nicht mehr notwendig.<\/li>\n<li>Sie widerrufen Ihre Einwilligung, auf die sich die Verarbeitung gem\u00e4\u00df Artikel 6 Absatz 1 DSGVO Buchstabe a oder Artikel 9 Absatz 2 Buchstabe a DSGVO st\u00fctzte, und es fehlt an einer anderweitigen Rechtsgrundlage f\u00fcr die Verarbeitung.<\/li>\n<li>Sie legen gem\u00e4\u00df Artikel 21 Absatz 1 DSGVO Widerspruch gegen die Verarbeitung ein und es liegen keine vorrangigen berechtigten Gr\u00fcnde f\u00fcr die Verarbeitung vor, oder Sie legen gem\u00e4\u00df Artikel 21 Absatz 2 DSGVO Widerspruch gegen die Verarbeitung ein.<\/li>\n<li>Die personenbezogenen Daten wurden unrechtm\u00e4\u00dfig verarbeitet.<\/li>\n<li>Die L\u00f6schung der personenbezogenen Daten ist zur Erf\u00fcllung einer rechtlichen Verpflichtung nach dem Unionsrecht oder dem Recht der Mitgliedstaaten erforderlich, dem wir unterliegen.<\/li>\n<li>Die personenbezogenen Daten wurden in Bezug auf angebotene Dienste der Informationsgesellschaft gem\u00e4\u00df Artikel 8 Absatz 1 DSGVO erhoben.<\/li>\n<\/ol>\n<p>Haben wir die personenbezogenen Daten \u00f6ffentlich gemacht und sind wir gem\u00e4\u00df zu deren L\u00f6schung verpflichtet, so treffen wir unter Ber\u00fccksichtigung der verf\u00fcgbaren Technologie und der Implementierungskosten angemessene Ma\u00dfnahmen, auch technischer Art, um f\u00fcr die Datenverarbeitung Verantwortliche, die die personenbezogenen Daten verarbeiten, dar\u00fcber zu informieren, dass Sie von ihnen die L\u00f6schung aller Links zu diesen personenbezogenen Daten oder von Kopien oder Replikationen dieser personenbezogenen Daten verlangt hat.<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt; color: #ff6600;\"><strong>Recht auf Einschr\u00e4nkung der Verarbeitung <\/strong><\/span><\/p>\n<p>Sie haben das Recht, von uns die Einschr\u00e4nkung der Verarbeitung zu verlangen, wenn eine der folgenden Voraussetzungen gegeben ist:<\/p>\n<ol>\n<li>die Richtigkeit der personenbezogenen Daten wird von Ihnen bestritten, und zwar f\u00fcr eine Dauer, die es uns erm\u00f6glicht, die Richtigkeit der personenbezogenen Daten zu \u00fcberpr\u00fcfen,<\/li>\n<li>die Verarbeitung unrechtm\u00e4\u00dfig ist und Sie die L\u00f6schung der personenbezogenen Daten ablehnten und stattdessen die Einschr\u00e4nkung der Nutzung der personenbezogenen Daten verlangt;<\/li>\n<li>wir die personenbezogenen Daten f\u00fcr die Zwecke der Verarbeitung nicht l\u00e4nger ben\u00f6tigen, Sie die Daten jedoch zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen ben\u00f6tigten, oder<\/li>\n<li>Sie Widerspruch gegen die Verarbeitung gem\u00e4\u00df Artikel 21 Absatz 1 DSGVO eingelegt haben, solange noch nicht feststeht, ob die berechtigten Gr\u00fcnde unseres Unternehmens gegen\u00fcber den Ihren \u00fcberwiegen.<\/li>\n<\/ol>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt; color: #ff6600;\"><strong>Recht auf Daten\u00fcbertragbarkeit <\/strong><\/span><\/p>\n<p>Sie haben das Recht, die Sie betreffenden personenbezogenen Daten, die uns bereitgestellt haben, in einem strukturierten, g\u00e4ngigen und maschinenlesbaren Format zu erhalten, und Sie haben das Recht, diese Daten einem anderen Verantwortlichen ohne Behinderung durch uns zu \u00fcbermitteln, sofern<\/p>\n<ol>\n<li>die Verarbeitung auf einer Einwilligung gem\u00e4\u00df Artikel 6 Absatz 1 Buchstabe a DSGVO oder Artikel 9 Absatz 2 Buchstabe a DSGVO oder auf einem Vertrag gem\u00e4\u00df Artikel 6 Absatz 1 Buchstabe b DSGVO beruht und<\/li>\n<li>die Verarbeitung mithilfe automatisierter Verfahren erfolgt.<\/li>\n<\/ol>\n<p>Bei der Aus\u00fcbung ihres Rechts auf Daten\u00fcbertragbarkeit gem\u00e4\u00df Absatz 1 haben Sie das Recht, zu erwirken, dass die personenbezogenen Daten direkt von uns einem anderen Verantwortlichen \u00fcbermittelt werden, soweit dies technisch machbar ist.<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt; color: #ff6600;\"><strong>Widerspruchsrecht <\/strong><\/span><\/p>\n<p>Sie haben das Recht, aus Gr\u00fcnden, die sich aus Ihrer besonderen Situation ergeben, jederzeit gegen die Verarbeitung sie betreffender personenbezogener Daten, die aufgrund von Artikel 6 Absatz 1 Buchstaben e oder f DSGVO erfolgt, Widerspruch einzulegen; dies gilt auch f\u00fcr ein auf diese Bestimmungen gest\u00fctztes Profiling. Wir verarbeiten die personenbezogenen Daten nicht mehr, es sei denn, wir k\u00f6nnen zwingende schutzw\u00fcrdige Gr\u00fcnde f\u00fcr die Verarbeitung nachweisen, die Ihre Interessen, Rechte und Freiheiten \u00fcberwiegen, oder die Verarbeitung dient der Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen.<\/p>\n<p>Werden personenbezogene Daten von uns verarbeitet, um Direktwerbung zu betreiben, so haben Sie das Recht, jederzeit Widerspruch gegen die Verarbeitung Sie betreffender personenbezogener Daten zum Zwecke derartiger Werbung einzulegen; dies gilt auch f\u00fcr das Profiling, soweit es mit solcher Direktwerbung in Verbindung steht.<\/p>\n<p>Sie haben das Recht, aus Gr\u00fcnden, die sich aus Ihrer besonderen Situation ergeben, gegen die Sie betreffende Verarbeitung sie betreffender personenbezogener Daten, die zu wissenschaftlichen oder historischen Forschungszwecken oder zu statistischen Zwecken gem\u00e4\u00df Artikel 89 Absatz 1 DSGVO erfolgt, Widerspruch einzulegen, es sei denn, die Verarbeitung ist zur Erf\u00fcllung einer im \u00f6ffentlichen Interesse liegenden Aufgabe erforderlich.<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt; color: #ff6600;\"><strong>Automatisierte En<\/strong><strong>tscheidungen einschlie\u00dflich Profiling<\/strong><\/span><\/p>\n<p>Sie haben das Recht, nicht einer ausschlie\u00dflich auf einer automatisierten Verarbeitung \u2013 einschlie\u00dflich Profiling \u2013 beruhenden Entscheidung unterworfen zu werden, die Ihnen gegen\u00fcber rechtliche Wirkung entfaltet oder Sie in \u00e4hnlicher Weise erheblich beeintr\u00e4chtigt.<\/p>\n<p><span style=\"font-size: 14pt; color: #ff6600; font-family: arial, helvetica, sans-serif;\"><strong>Recht auf Widerruf einer datenschutzrechtlichen Einwilligung <\/strong><\/span><\/p>\n<p>Sie haben das Recht, eine Einwilligung zur Verarbeitung personenbezogener Daten jederzeit zu widerrufen.<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt; color: #ff6600;\"><strong>Recht auf Beschwerde bei einer Aufsichtsbeh\u00f6rde <\/strong><\/span><\/p>\n<p>Sie haben das Recht auf Beschwerde bei einer Aufsichtsbeh\u00f6rde, insbesondere in dem Mitgliedstaat ihres Aufenthaltsorts, ihres Arbeitsplatzes oder des Orts des mutma\u00dflichen Versto\u00dfes, Sie der Ansicht sind, dass die Verarbeitung der Sie betreffenden personenbezogenen Daten rechtswidrig ist.<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt; color: #ff6600;\"><strong>Datensicherheit <\/strong><\/span><\/p>\n<p>Wir sind um die Sicherheit Ihrer Daten im Rahmen der geltenden Datenschutzgesetze und technischen M\u00f6glichkeiten maximal bem\u00fcht. Ihre pers\u00f6nlichen Daten werden bei uns verschl\u00fcsselt \u00fcbertragen. Dies gilt f\u00fcr Ihre Bestellungen und auch f\u00fcr das Kundenlogin. Wir nutzen das Codierungssystems SSL (Secure Socket Layer), weisen jedoch darauf hin, dass die Daten\u00fcbertragung im Internet (z.B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich. Zur Sicherung Ihrer Daten unterhalten wir technische- und organisatorische Sicherungsma\u00dfnahmen, die wir immer wieder dem Stand der Technik anpassen. Wir gew\u00e4hrleisten au\u00dferdem nicht, dass unser Angebot zu bestimmten Zeiten zur Verf\u00fcgung steht; St\u00f6rungen, Unterbrechungen oder Ausf\u00e4lle k\u00f6nnen nicht ausgeschlossen werden. Die von uns verwendeten Server werden regelm\u00e4\u00dfig sorgf\u00e4ltig gesichert.<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt; color: #ff6600;\"><strong>Automatisierte Entscheidungsfindung <\/strong><\/span><\/p>\n<p>Eine automatisierte Entscheidungsfindung auf der Grundlage der erhobenen personenbezogenen Daten findet nicht statt.<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt; color: #ff6600;\"><strong>Weitergabe von Daten an Dritte, Keine Daten\u00fcbertragung ins Nicht-EU-Ausland<\/strong><\/span><\/p>\n<p>Grunds\u00e4tzlich verwenden wir Ihre personenbezogenen Daten nur innerhalb unseres Unternehmens.<\/p>\n<p>Wenn und soweit wir Dritte im Rahmen der Erf\u00fcllung von Vertr\u00e4gen einschalten (etwa Logistik-Dienstleister) erhalten diese personenbezogenen Daten nur in dem Umfang, in welchem die \u00dcbermittlung f\u00fcr die entsprechende Leistung erforderlich ist.<\/p>\n<p>F\u00fcr den Fall, dass wir bestimmte Teile der Datenverarbeitung auslagern (\u201eAuftragsverarbeitung\u201c), verpflichten wir Auftragsverarbeiter vertraglich dazu, personenbezogene Daten nur im Einklang mit den Anforderungen der Datenschutzgesetze zu verwenden und den Schutz der Rechte der betroffenen Person zu gew\u00e4hrleisten.<\/p>\n<p>Eine Daten\u00fcbertragung an Stellen oder Personen au\u00dferhalb der EU au\u00dferhalb der in dieser Erkl\u00e4rung in Punkt <strong>Google Analytics<\/strong> genannten F\u00e4llen findet nicht statt und ist nicht geplant.<\/p>\n<p><span style=\"color: #ff6600;\"><strong>Stand 17.05.2018<\/strong><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Datenschutzerkl\u00e4rung Die nachfolgende Datenschutzerkl\u00e4rung gilt f\u00fcr die Nutzung der Webseite www.c-w-stolte.de (nachfolgend \u201eWebsite\u201c). Wir messen dem Datenschutz gro\u00dfe Bedeutung bei. Die Erhebung und Verarbeitung Ihrer personenbezogenen<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/c-w-stolte.de\/en\/wp-json\/wp\/v2\/pages\/127"}],"collection":[{"href":"https:\/\/c-w-stolte.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/c-w-stolte.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/c-w-stolte.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/c-w-stolte.de\/en\/wp-json\/wp\/v2\/comments?post=127"}],"version-history":[{"count":5,"href":"https:\/\/c-w-stolte.de\/en\/wp-json\/wp\/v2\/pages\/127\/revisions"}],"predecessor-version":[{"id":418,"href":"https:\/\/c-w-stolte.de\/en\/wp-json\/wp\/v2\/pages\/127\/revisions\/418"}],"wp:attachment":[{"href":"https:\/\/c-w-stolte.de\/en\/wp-json\/wp\/v2\/media?parent=127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}